{"id":62152,"date":"2024-01-09T14:54:24","date_gmt":"2024-01-09T14:54:24","guid":{"rendered":"https:\/\/www.alongavecanna.com\/?p=62152"},"modified":"2024-01-09T14:57:52","modified_gmt":"2024-01-09T14:57:52","slug":"inspirations-slow-living-pour-lhiver","status":"publish","type":"post","link":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/","title":{"rendered":"Inspirations \u00ab\u00a0slow living\u00a0\u00bb pour l&rsquo;hiver"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"62152\" class=\"elementor elementor-62152 elementor-62151\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48ed27a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48ed27a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e0e553c\" data-id=\"2e0e553c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-150045c0 elementor-widget elementor-widget-text-editor\" data-id=\"150045c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">L&rsquo;hiver est une saison d&rsquo;hibernation, et alors que dans notre monde moderne nous sommes encourag\u00e9s \u00e0 continuer \u00e0 maintenir un rythme effr\u00e9n\u00e9 et rester productifs, le tricot peut nous apprendre \u00e0 nous ralentir. M\u00eame s&rsquo;il existe de nombreuses raisons de se mettre au tricot, se ralentir et prendre du temps pour soi font parmi les principaux bienfaits. Cet \u00e9tat d&rsquo;esprit a des implications qui vont bien au-del\u00e0 du tricot. Cet hiver, j&rsquo;aimerais vous encourager \u00e0 trouver des moyens d&rsquo;\u00e9chapper \u00e0 productivit\u00e9 constante, et de vous inspirer du monde naturel en trouvant des moments de calme, de lenteur et de repos. J&rsquo;esp\u00e8re que vous trouverez de l&rsquo;inspiration dans ces id\u00e9es !<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04c88b4 elementor-widget elementor-widget-heading\" data-id=\"04c88b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.themindfulapothecary.co.uk\/products\/lemon-verbena-bay-basil-garden-candle-bowl\" target=\"_blank\"><span style=\"font-size: 13pt;font-family: Arial;background-color: transparent;vertical-align: baseline\">1. Portez vos tricots en laine pour faire une longue promenade hivernale<\/span><\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dfc57f elementor-widget elementor-widget-image\" data-id=\"5dfc57f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/elementor\/thumbs\/anna-31-scaled-qfsav10b23j41af1jzj6helnj1y3kgx65mpqq32ey0.jpg\" title=\"anna-31\" alt=\"anna-31\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e445ec8 elementor-widget elementor-widget-text-editor\" data-id=\"e445ec8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nous sommes naturellement plus l\u00e9thargiques en hiver et le sport intense peut ne pas \u00eatre agr\u00e9able \u00e0 cette p\u00e9riode de l&rsquo;ann\u00e9e. D&rsquo;un autre c\u00f4t\u00e9, nous pouvons \u00eatre tent\u00e9s de nous r\u00e9fugier \u00e0 l&rsquo;int\u00e9rieur et de nous cacher totalement du froid dehors (j&rsquo;en suis certainement coupable). Mais l&rsquo;hiver a certainement sa propre beaut\u00e9 et sortir se promener est le moyen id\u00e9al de faire un peu de sport tout en profitant du paysage hivernal. N&rsquo;oubliez pas de vous emmitoufler dans tous vos v\u00eatements en laine &#8211; c&rsquo;est l\u00e0 que le fait d&rsquo;\u00eatre tricoteur s&rsquo;av\u00e8re utile ! <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7019d2e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7019d2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c8922d elementor-widget elementor-widget-heading\" data-id=\"4c8922d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/mindthecork.com\/products\/onda-sol-cork-vase-duo\" target=\"_blank\"><font color=\"#000000\" face=\"Arial\"><span style=\"font-size: 17.3333px\">2. Passez du temps sans votre portable ou vos appareils \u00e9lectroniques<\/span><\/font><\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50221bb elementor-widget elementor-widget-text-editor\" data-id=\"50221bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Il n&rsquo;y a rien qui interrompe votre calme comme le bourdonnement des notifications qui vous rappellent les choses que vous n&rsquo;avez pas faites, les personnes \u00e0 qui vous devez r\u00e9pondre et le flux incessant de nouvelles. Et nous n&rsquo;avons pas besoin de nous retirer dans une cabane hors r\u00e9seau pour retrouver un peu de paix Parfois, le simple fait de mettre notre portable en mode silencieux pendant une journ\u00e9e, ou m\u00eame une heure, peut faire toute la diff\u00e9rence. Pourquoi pas essayer pour voir l&rsquo;impact sur votre \u00e9tat d&rsquo;esprit? <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fa9fde elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8fa9fde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3908223 elementor-widget elementor-widget-heading\" data-id=\"3908223\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/mindthecork.com\/products\/onda-sol-cork-vase-duo\" target=\"_blank\"><font color=\"#000000\" face=\"Arial\"><span style=\"font-size: 17.3333px\">3. Faites du pain maison<\/span><\/font><\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc8e60e elementor-widget elementor-widget-image\" data-id=\"cc8e60e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/elementor\/thumbs\/tree-bread-qh353ud97xuhofab2h6v398v89mz1ztxakkk1dfju0.jpg\" title=\"tree bread\" alt=\"tree bread\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b922950 elementor-widget elementor-widget-text-editor\" data-id=\"b922950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">En cherchant toujours le moyen le plus rapide de faire des choses dans votre vie moderne, qu&rsquo;est-ce que nous avons perdu ? Certes, nous pouvons acheter du pain au supermarch\u00e9, tout comme nous pouvons acheter des v\u00eatements tricot\u00e9s \u00e0 la machine, mais nous n&rsquo;aurons pas la satisfaction de la lenteur du processus. C&rsquo;est pour cette raison que j&rsquo;aime faire mon propre pain. Je travaille mon pain pendant trois jours, laissant le temps faire le travail de fermentation, et r\u00e9coltant les saveurs et les avantages nutritionnels dans le produit final (comme le montre ma derni\u00e8re cuisson ci-dessus !). Si vous \u00eates \u00e0 la recherche d&rsquo;un nouveau d\u00e9fi, pourquoi ne pas essayer ? Vous pouvez apprendre \u00e0 faire votre levain <\/span><a href=\"https:\/\/www.pantrymama.com\/making-a-sourdough-starter\/\"><strong><span style=\"text-decoration: underline;\">ici<\/span><\/strong><\/a><span style=\"font-weight: 400;\"> et il y a une recette pour d\u00e9butants <\/span><a href=\"https:\/\/www.pantrymama.com\/how-to-bake-simple-sourdough-bread\/\"><strong><span style=\"text-decoration: underline;\">ici<\/span><\/strong><\/a><span style=\"font-weight: 400;\"><strong><span style=\"text-decoration: underline;\">.<\/span><\/strong> Si vous souhaitez simplement vous initier, vous pouvez vous contenter d&rsquo;un simple pain \u00e0 la levure commerciale,<\/span><a href=\"https:\/\/www.bbcgoodfood.com\/recipes\/easy-white-bread\"><strong><span style=\"text-decoration: underline;\">comme celui-ci. <\/span><\/strong><\/a> <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-307b889 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"307b889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-403fa6e elementor-widget elementor-widget-heading\" data-id=\"403fa6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/baxbees.co.uk\/shop\/multifloralhoney\/july-blossom-honey\/\" target=\"_blank\"><font color=\"#000000\" face=\"Arial\"><span style=\"font-size: 17.3333px\">4. Dormez plus longtemps<\/span><\/font><\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9de2cd3 elementor-widget elementor-widget-text-editor\" data-id=\"9de2cd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Avec des journ\u00e9es plus courtes et des nuits plus longues, ce n&rsquo;est pas pour rien que nous sommes souvent plus fatigu\u00e9s en hiver ! Et ce n&rsquo;est pas forc\u00e9ment quelque chose que nous devons ignorer. Prendre le temps de se reposer n&rsquo;est pas de la paresse. En tant que cr\u00e9atures cycliques, nos besoins de repos varient selon les saisons. Alors, mettez votre r\u00e9veil un peu plus tard, faites une petite grasse matin\u00e9e le week-end, ou blottissez-vous dans votre lit avec une bouillotte un peu plus t\u00f4t que vous ne le feriez en \u00e9t\u00e9. Votre niveau d&rsquo;\u00e9nergie pendant la journ\u00e9e vous remerciera !<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35deddc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"35deddc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06910bb elementor-widget elementor-widget-heading\" data-id=\"06910bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.marthabrook.com\/product\/leather-effect-gardening-journal\/\" target=\"_blank\"><font color=\"#000000\" face=\"Arial\"><span style=\"font-size: 17.3333px\">5. Tenez un journal intime<\/span><\/font><\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c14e75c elementor-widget elementor-widget-image\" data-id=\"c14e75c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/priscilla-du-preez-CeW-PHwpGc-unsplash-1024x683.jpg\" class=\"attachment-large size-large wp-image-62148\" alt=\"\" srcset=\"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/priscilla-du-preez-CeW-PHwpGc-unsplash-1024x683.jpg 1024w, https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/priscilla-du-preez-CeW-PHwpGc-unsplash-300x200.jpg 300w, https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/priscilla-du-preez-CeW-PHwpGc-unsplash-768x512.jpg 768w, https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/priscilla-du-preez-CeW-PHwpGc-unsplash-1536x1024.jpg 1536w, https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/priscilla-du-preez-CeW-PHwpGc-unsplash-2048x1365.jpg 2048w, https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/priscilla-du-preez-CeW-PHwpGc-unsplash-600x400.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142b770 elementor-widget elementor-widget-text-editor\" data-id=\"142b770\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le ralentissement est une condition pr\u00e9alable \u00e0 l&rsquo;autor\u00e9flexion. Si nous sommes constamment pris dans l&rsquo;urgence, nous nous privons de la possibilit\u00e9 de r\u00e9fl\u00e9chir \u00e0 ce que nous ressentons vraiment et \u00e0 ce dont nous avons vraiment besoin et envie dans notre vie. L&rsquo;hiver est un moment naturel pour se tourner vers l&rsquo;int\u00e9rieur et un journal intime est un outil tr\u00e8s efficace pour le faire ! Le simple fait de prendre dix minutes par jour pour s&rsquo;asseoir avec un stylo et du papier, avec pour seule compagnie nos pens\u00e9es, peut tout changer ! Et si vous voulez r\u00e9fl\u00e9chir sur votre vie tricot, n&rsquo;h\u00e9sitez pas \u00e0 lire mon article : <a href=\"https:\/\/www.alongavecanna.com\/fr\/2023\/01\/27\/invitations-a-tenir-un-journal-pour-les-tricoteurs-euses-attentives\/\"><strong><span style=\"text-decoration: underline;\">Invitations \u00e0 tenir un journal pour des tricoteurs\/euses attentifs.<\/span><\/strong><\/a> <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8cfad1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f8cfad1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-953e824 elementor-widget elementor-widget-heading\" data-id=\"953e824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.marthabrook.com\/product\/leather-effect-gardening-journal\/\" target=\"_blank\"><font color=\"#000000\" face=\"Arial\"><span style=\"font-size: 17.3333px\">6. S'offrir un caf\u00e9 en solo<\/span><\/font><\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44fd3fc elementor-widget elementor-widget-image\" data-id=\"44fd3fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/elementor\/thumbs\/guy-basabose-FzdEbrA3Qj0-unsplash-scaled-qh35400a2f4gtcz9v457s917gukzm7024s41h373o8.jpg\" title=\"guy-basabose-FzdEbrA3Qj0-unsplash\" alt=\"guy-basabose-FzdEbrA3Qj0-unsplash\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-730d525 elementor-widget elementor-widget-text-editor\" data-id=\"730d525\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Passez du temps tout seul nous permet de nous asseoir avec nos pens\u00e9es, ce qui n&rsquo;est pas possible en compagnie d&rsquo;autres personnes. Alors, allez dans votre caf\u00e9 pr\u00e9f\u00e9r\u00e9, trouvez un coin confortable et, pendant que vous \u00eates assis, mettez-vous au d\u00e9fi de ne pas vous occuper de votre t\u00e9l\u00e9phone ou de quoi que ce soit. Prenez le temps de savourer la boisson chaude de votre choix, de remarquer votre environnement et d&rsquo;observer les gens.<\/span><span style=\"font-weight: 400;\">.  <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f48d87b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f48d87b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-564ed17 elementor-widget elementor-widget-heading\" data-id=\"564ed17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.teaspoon-tea.co.uk\/products\/summer-tea-loose-leaf-tea\" target=\"_blank\"><font color=\"#000000\" face=\"Arial\"><span style=\"font-size: 17.3333px\">7. Allumer (ou fabriquer !) une bougie<\/span><\/font><\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1ae9b5 elementor-widget elementor-widget-image\" data-id=\"e1ae9b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/elementor\/thumbs\/annie-spratt-MOJ4P-omCkY-unsplash-scaled-qh353edzzr7h9v8xzmxacnm0d0xbvd44dehmtr1aoo.jpg\" title=\"annie-spratt-MOJ4P-omCkY-unsplash\" alt=\"annie-spratt-MOJ4P-omCkY-unsplash\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3053d85 elementor-widget elementor-widget-text-editor\" data-id=\"3053d85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Allumer une bougie est un merveilleux rituel hivernal, pour les matins froids ou les soir\u00e9es bien au chaud \u00e0 l&rsquo;int\u00e9rieur. Le fait de prendre le temps de cr\u00e9er une ambiance et peut-\u00eatre de prendre quelques minutes pour regarder la flamme peut \u00eatre un moment de soin de soi et d&rsquo;attention que vous vous r\u00e9servez dans votre journ\u00e9e. Nos bougies pr\u00e9f\u00e9r\u00e9es proviennent de <a href=\"https:\/\/www.thebotanicalcandleco.co.uk\/\"><strong><span style=\"text-decoration: underline;\">The Botanical Candle Co.<\/span><\/strong><\/a> et de <a href=\"https:\/\/www.themindfulapothecary.co.uk\/\"><span style=\"text-decoration: underline;\"><strong>The Mindful Apothecary<\/strong><\/span><\/a>mais si vous vous avez envie, vous pouvez fabriquer le v\u00f4tre ! M\u00e9langez \u00e0 parts \u00e9gales de la cire d&rsquo;abeille et de l&rsquo;huile de coco au bain-marie, ajoutez les huiles essentielles de votre choix et versez le tout dans un vieux bocal muni d&rsquo;une m\u00e8che (je pr\u00e9f\u00e8re les m\u00e8ches en bois pour leur cr\u00e9pitement).<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-025e4cb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"025e4cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbe49a6 elementor-widget elementor-widget-heading\" data-id=\"fbe49a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.teaspoon-tea.co.uk\/products\/summer-tea-loose-leaf-tea\" target=\"_blank\"><font color=\"#000000\" face=\"Arial\"><span style=\"font-size: 17.3333px\">8. Refusez une invitation<\/span><\/font><\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c2763 elementor-widget elementor-widget-text-editor\" data-id=\"73c2763\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La vie lente ne consiste pas \u00e0 faire <\/span><i><span style=\"font-weight: 400;\">toutes les choses<\/span><\/i><span style=\"font-weight: 400;\">mais \u00e0 un rythme un peu plus lent. Il s&rsquo;agit de se mettre \u00e0 l&rsquo;\u00e9coute de nos priorit\u00e9s et d&rsquo;y voir clair, de conna\u00eetre les aspects de notre vie que nous trouvons plus ou moins importants. Personne ne peut ni ne doit \u00ab\u00a0tout avoir\u00a0\u00bb. Parfois, il s&rsquo;agit de refuser quelque chose pour prendre du temps pour soi ou pour les personnes qui vous apportent de la joie. En laissant tomber certaines attentes et obligations, nous pouvons consacrer plus de temps aux choses et aux personnes qui comptent le plus pour nous et nous pouvons passer ce temps moins stress\u00e9 et plus pr\u00e9sent !<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66148a8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"66148a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2b3b37 elementor-widget elementor-widget-text-editor\" data-id=\"d2b3b37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Quels sont vos moyens pr\u00e9f\u00e9r\u00e9s pour vous ralentir et rester pr\u00e9sent pendant les mois d&rsquo;hiver ? Avez-vous des rituels ou des habitudes particuli\u00e8res ? Dites-nous ce que vous en pensez dans les commentaires !&nbsp;<\/strong><\/p>\n<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; letter-spacing: 0px;\"><b>Comme toujours, n&rsquo;h\u00e9sitez pas \u00e0 nous laisser des commentaires ci-dessous ou sur Instagram ! Vous pouvez nous taguer @along.avec.anna ou utiliser le #alongavecanna !<\/b><\/span><\/p>\n<p><b>Restez au chaud !<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e939b8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2e939b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9980e4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9980e4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd7cc3\" data-id=\"0fd7cc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4706c30 elementor-widget elementor-widget-text-editor\" data-id=\"4706c30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Sarah xxx<\/strong><\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L&rsquo;hiver est une saison d&rsquo;hibernation, et alors que dans notre monde moderne nous sommes encourag\u00e9s \u00e0 continuer \u00e0 maintenir un rythme effr\u00e9n\u00e9 et rester productifs, le tricot peut nous apprendre \u00e0 nous ralentir. M\u00eame s&rsquo;il existe de nombreuses raisons de se mettre au tricot, se ralentir et prendre du temps pour soi font parmi les [&hellip;]<\/p>\n","protected":false},"author":10909,"featured_media":62154,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[326,619],"tags":[617,596,602,618,336],"class_list":["post-62152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-fr","category-en-vedette","tag-acheter-independant","tag-exeter-fr","tag-royaume-uni","tag-soutenir-les-petites-entreprises","tag-tricot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inspirations &quot;slow living&quot; pour l&#039;hiver - Along Avec Anna<\/title>\n<meta name=\"description\" content=\"L&#039;hiver est une p\u00e9riode d&#039;hibernation, de ralentissement et de r\u00e9flexion. Cet article est plein d&#039;id\u00e9es pour vous aider \u00e0 rester pr\u00e9sent et \u00e0 profiter du calme de la saison.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inspirations &quot;slow living&quot; pour l&#039;hiver - Along Avec Anna\" \/>\n<meta property=\"og:description\" content=\"L&#039;hiver est une p\u00e9riode d&#039;hibernation, de ralentissement et de r\u00e9flexion. Cet article est plein d&#039;id\u00e9es pour vous aider \u00e0 rester pr\u00e9sent et \u00e0 profiter du calme de la saison.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/\" \/>\n<meta property=\"og:site_name\" content=\"Along Avec Anna\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/alongavecanna\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-09T14:54:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-09T14:57:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sarah\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/\"},\"author\":{\"name\":\"Sarah\",\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/#\\\/schema\\\/person\\\/20abd932df4134b62b396dfbef2c69bd\"},\"headline\":\"Inspirations \u00ab\u00a0slow living\u00a0\u00bb pour l&rsquo;hiver\",\"datePublished\":\"2024-01-09T14:54:24+00:00\",\"dateModified\":\"2024-01-09T14:57:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/\"},\"wordCount\":1177,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alongavecanna.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg\",\"keywords\":[\"acheter ind\u00e9pendant\",\"Exeter\",\"ROYAUME-UNI\",\"soutenir les petites entreprises\",\"tricot\"],\"articleSection\":[\"Blog\",\"En vedette\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/\",\"url\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/\",\"name\":\"Inspirations \\\"slow living\\\" pour l'hiver - Along Avec Anna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alongavecanna.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg\",\"datePublished\":\"2024-01-09T14:54:24+00:00\",\"dateModified\":\"2024-01-09T14:57:52+00:00\",\"description\":\"L'hiver est une p\u00e9riode d'hibernation, de ralentissement et de r\u00e9flexion. Cet article est plein d'id\u00e9es pour vous aider \u00e0 rester pr\u00e9sent et \u00e0 profiter du calme de la saison.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alongavecanna.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.alongavecanna.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg\",\"width\":2560,\"height\":1945},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/2024\\\/01\\\/09\\\/inspirations-slow-living-pour-lhiver\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inspirations \u00ab\u00a0slow living\u00a0\u00bb pour l&rsquo;hiver\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/\",\"name\":\"Along Avec Anna\",\"description\":\"Ethical yarn &amp; timeless knitting patterns\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/#organization\",\"name\":\"Along Avec Anna\",\"url\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alongavecanna.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-along-avec-anna.png\",\"contentUrl\":\"https:\\\/\\\/www.alongavecanna.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-along-avec-anna.png\",\"width\":1728,\"height\":627,\"caption\":\"Along Avec Anna\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/alongavecanna\",\"https:\\\/\\\/www.instagram.com\\\/along.avec.anna\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/#\\\/schema\\\/person\\\/20abd932df4134b62b396dfbef2c69bd\",\"name\":\"Sarah\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e694a833103b88345b64bf79afbcdfcd8168b8d0edfbaf35c7df68f8c654b203?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e694a833103b88345b64bf79afbcdfcd8168b8d0edfbaf35c7df68f8c654b203?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e694a833103b88345b64bf79afbcdfcd8168b8d0edfbaf35c7df68f8c654b203?s=96&d=mm&r=g\",\"caption\":\"Sarah\"},\"url\":\"https:\\\/\\\/www.alongavecanna.com\\\/fr\\\/author\\\/thebestteammate\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inspirations \"slow living\" pour l'hiver - Along Avec Anna","description":"L'hiver est une p\u00e9riode d'hibernation, de ralentissement et de r\u00e9flexion. Cet article est plein d'id\u00e9es pour vous aider \u00e0 rester pr\u00e9sent et \u00e0 profiter du calme de la saison.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/","og_locale":"fr_FR","og_type":"article","og_title":"Inspirations \"slow living\" pour l'hiver - Along Avec Anna","og_description":"L'hiver est une p\u00e9riode d'hibernation, de ralentissement et de r\u00e9flexion. Cet article est plein d'id\u00e9es pour vous aider \u00e0 rester pr\u00e9sent et \u00e0 profiter du calme de la saison.","og_url":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/","og_site_name":"Along Avec Anna","article_publisher":"https:\/\/facebook.com\/alongavecanna","article_published_time":"2024-01-09T14:54:24+00:00","article_modified_time":"2024-01-09T14:57:52+00:00","og_image":[{"width":2560,"height":1945,"url":"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Sarah","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sarah","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/#article","isPartOf":{"@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/"},"author":{"name":"Sarah","@id":"https:\/\/www.alongavecanna.com\/fr\/#\/schema\/person\/20abd932df4134b62b396dfbef2c69bd"},"headline":"Inspirations \u00ab\u00a0slow living\u00a0\u00bb pour l&rsquo;hiver","datePublished":"2024-01-09T14:54:24+00:00","dateModified":"2024-01-09T14:57:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/"},"wordCount":1177,"commentCount":0,"publisher":{"@id":"https:\/\/www.alongavecanna.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg","keywords":["acheter ind\u00e9pendant","Exeter","ROYAUME-UNI","soutenir les petites entreprises","tricot"],"articleSection":["Blog","En vedette"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/","url":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/","name":"Inspirations \"slow living\" pour l'hiver - Along Avec Anna","isPartOf":{"@id":"https:\/\/www.alongavecanna.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/#primaryimage"},"image":{"@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg","datePublished":"2024-01-09T14:54:24+00:00","dateModified":"2024-01-09T14:57:52+00:00","description":"L'hiver est une p\u00e9riode d'hibernation, de ralentissement et de r\u00e9flexion. Cet article est plein d'id\u00e9es pour vous aider \u00e0 rester pr\u00e9sent et \u00e0 profiter du calme de la saison.","breadcrumb":{"@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/#primaryimage","url":"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg","contentUrl":"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/12\/alex-padurariu-k0SwnevO_wk-unsplash-scaled.jpg","width":2560,"height":1945},{"@type":"BreadcrumbList","@id":"https:\/\/www.alongavecanna.com\/fr\/2024\/01\/09\/inspirations-slow-living-pour-lhiver\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alongavecanna.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Inspirations \u00ab\u00a0slow living\u00a0\u00bb pour l&rsquo;hiver"}]},{"@type":"WebSite","@id":"https:\/\/www.alongavecanna.com\/fr\/#website","url":"https:\/\/www.alongavecanna.com\/fr\/","name":"Along Avec Anna","description":"Ethical yarn &amp; timeless knitting patterns","publisher":{"@id":"https:\/\/www.alongavecanna.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alongavecanna.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.alongavecanna.com\/fr\/#organization","name":"Along Avec Anna","url":"https:\/\/www.alongavecanna.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.alongavecanna.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/01\/logo-along-avec-anna.png","contentUrl":"https:\/\/www.alongavecanna.com\/wp-content\/uploads\/2023\/01\/logo-along-avec-anna.png","width":1728,"height":627,"caption":"Along Avec Anna"},"image":{"@id":"https:\/\/www.alongavecanna.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/alongavecanna","https:\/\/www.instagram.com\/along.avec.anna\/"]},{"@type":"Person","@id":"https:\/\/www.alongavecanna.com\/fr\/#\/schema\/person\/20abd932df4134b62b396dfbef2c69bd","name":"Sarah","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e694a833103b88345b64bf79afbcdfcd8168b8d0edfbaf35c7df68f8c654b203?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e694a833103b88345b64bf79afbcdfcd8168b8d0edfbaf35c7df68f8c654b203?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e694a833103b88345b64bf79afbcdfcd8168b8d0edfbaf35c7df68f8c654b203?s=96&d=mm&r=g","caption":"Sarah"},"url":"https:\/\/www.alongavecanna.com\/fr\/author\/thebestteammate\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/posts\/62152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/users\/10909"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/comments?post=62152"}],"version-history":[{"count":0,"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/posts\/62152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/media\/62154"}],"wp:attachment":[{"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/media?parent=62152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/categories?post=62152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alongavecanna.com\/fr\/wp-json\/wp\/v2\/tags?post=62152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}